{"id":1593,"count":1,"description":"Se\u00e7\u00e3o Taioba ES.","link":"https:\/\/precota.com.br\/agro\/categoria\/ceasa\/ceasa-vitoria\/hortalicas-es\/taio-es\/","name":"Taioba ES","slug":"taio-es","taxonomy":"category","parent":412,"meta":[],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories\/1593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories\/412"}],"wp:post_type":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts?categories=1593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}