{"id":13065,"date":"2020-11-17T09:41:12","date_gmt":"2020-11-17T09:41:12","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=13065"},"modified":"2026-03-15T12:07:04","modified_gmt":"2026-03-15T12:07:04","slug":"grafico-preco-tabela-uva-nubia-ceasa-uberlandia-cx-5-kg","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-uva-nubia-ceasa-uberlandia-cx-5-kg\/","title":{"rendered":"Pre\u00e7o Uva Nubia cx 5 kg Ceasa Uberl\u00e2ndia"},"content":{"rendered":"<p>Uva Nubia (cx 5 kg), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Uberl\u00e2ndia (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 89.00 (cx 5 kg)<\/strong>* no dia 05\/01\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma queda de -8.99% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 97.00. Este produto n\u00e3o teve atualiza\u00e7\u00f5es de pre\u00e7o nos \u00faltimos meses. Verifique no <a href=\"https:\/\/precota.com.br\/agro\/\">\u00edndice<\/a> outras unidades Ceasa para informa\u00e7\u00f5es mais atualizadas. Veja mais detalhes, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceasa<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>05 de janeiro de 2026<\/td>\n<td>89.00<\/td>\n<td>89.00<\/td>\n<td>89.00<\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Gr\u00e1fico de pre\u00e7os recentes do produto Uva Nubia cx 5 kg<\/h3>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,2,17),72.00,72.00,72.00],[new Date(2025,2,20),72.00,72.00,72.00],[new Date(2025,2,27),83.00,83.00,83.00],[new Date(2025,2,31),73.00,73.00,73.00],[new Date(2025,6,14),55.00,55.00,55.00],[new Date(2025,11,08),66.00,66.00,66.00],[new Date(2025,11,11),66.00,66.00,66.00],[new Date(2025,11,26),89.00,89.00,89.00],[new Date(2025,11,29),97.00,97.00,97.00],[new Date(2026,0,05),89.00,89.00,89.00] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Uva Nubia cx 5 kg: Pre\u00e7os Ceasa Uberl\u00e2ndia - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 30}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ -0.00%. Unidade: (cx 5 kg). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h3>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h3>\n<table class=\"pClassNove\">\n<caption>\u00daltimos Pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td colspan=\"5\">Cota\u00e7\u00e3o n\u00e3o encontrada nos \u00faltimos 30 dias.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de julho de 2025<\/td>\n<td>55.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de julho de 2025<\/td>\n<td><\/td>\n<td>55.00<\/td>\n<td><\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de julho de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>55.00<\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>29 de dezembro de 2025<\/td>\n<td>97.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>29 de dezembro de 2025<\/td>\n<td><\/td>\n<td>97.00<\/td>\n<td><\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>29 de dezembro de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>97.00<\/td>\n<td>cx 5 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Uva Nubia cx 5 kg'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceasa Uberl\u00e2ndia &#8211; MG. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uva Nubia (cx 5 kg), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Uberl\u00e2ndia (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 89.00 (cx 5 kg)* no dia 05\/01\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma queda de -8.99% em rela\u00e7\u00e3o ao&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2020,2021,2180],"tags":[],"class_list":["post-13065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceasa","category-ceasa-mg","category-frutas-mg","category-uva-mg"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/13065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=13065"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/13065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media\/6109"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=13065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=13065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=13065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}