{"id":14533,"date":"2020-11-17T15:11:55","date_gmt":"2020-11-17T15:11:55","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=14533"},"modified":"2026-03-15T12:32:46","modified_gmt":"2026-03-15T12:32:46","slug":"grafico-preco-tabela-chiova-ceagesp-kg","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-chiova-ceagesp-kg\/","title":{"rendered":"Ceagesp pre\u00e7os Chiova kg"},"content":{"rendered":"<p>Pre\u00e7o Chiova kg, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 9.50 (kg)<\/strong> no dia 09\/03\/2026*, de acordo com o boletim Ceagesp, o que representa um aumento de 5.26% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 9.00. Veja mais detalhes Ceagesp, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>09 de mar\u00e7o de 2026<\/td>\n<td>9.00<\/td>\n<td>9.50<\/td>\n<td>10.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Gr\u00e1fico de pre\u00e7os recentes do produto Chiova kg<\/h2>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,2,17),15.00,17.00,20.00],[new Date(2025,2,19),18.00,19.00,20.00],[new Date(2025,2,21),10.00,13.00,15.00],[new Date(2025,2,24),13.00,14.00,15.00],[new Date(2025,2,26),8.00,9.00,10.00],[new Date(2025,3,04),13.00,14.00,15.00],[new Date(2025,3,07),8.00,9.00,10.00],[new Date(2025,3,09),10.00,13.00,15.00],[new Date(2025,3,16),13.00,14.00,15.00],[new Date(2025,3,28),8.00,9.00,10.00],[new Date(2025,4,07),8.00,9.00,10.00],[new Date(2025,4,12),8.00,9.00,10.00],[new Date(2025,4,16),4.50,4.75,5.00],[new Date(2025,4,19),8.00,9.00,10.00],[new Date(2025,4,21),14.00,15.00,16.00],[new Date(2025,4,23),4.00,4.50,5.00],[new Date(2025,4,26),6.00,7.00,8.00],[new Date(2025,4,28),7.00,7.50,8.00],[new Date(2025,5,25),6.00,7.00,8.00],[new Date(2025,5,30),10.00,12.00,12.00],[new Date(2025,6,11),4.00,4.50,5.00],[new Date(2025,6,14),5.00,6.00,6.00],[new Date(2025,6,16),25.00,28.00,30.00],[new Date(2025,6,21),11.00,12.00,13.00],[new Date(2025,6,25),8.00,9.00,10.00],[new Date(2025,6,28),8.22,9.89,12.34],[new Date(2025,6,30),4.00,4.50,5.00],[new Date(2025,7,13),3.00,4.00,5.00],[new Date(2025,7,15),9.00,9.50,10.00],[new Date(2025,7,18),6.00,7.00,8.00],[new Date(2025,7,20),8.00,9.00,10.00],[new Date(2025,7,22),3.00,4.00,5.00],[new Date(2025,7,27),3.00,4.00,4.00],[new Date(2025,7,29),5.00,5.50,6.00],[new Date(2025,8,01),3.00,4.00,5.00],[new Date(2025,8,03),4.00,5.00,6.00],[new Date(2025,8,05),4.00,5.00,6.00],[new Date(2025,8,08),4.50,4.80,5.00],[new Date(2025,8,10),3.00,4.98,5.00],[new Date(2025,8,17),5.00,7.00,10.00],[new Date(2025,8,22),4.00,4.50,5.00],[new Date(2025,8,24),4.00,4.50,5.00],[new Date(2025,8,26),5.00,6.00,7.00],[new Date(2025,8,29),8.00,9.00,10.00],[new Date(2025,9,01),5.19,5.72,6.25],[new Date(2025,9,03),8.00,9.00,10.00],[new Date(2025,9,08),5.24,5.48,6.11],[new Date(2025,9,10),6.00,6.56,7.11],[new Date(2025,9,15),4.80,4.90,5.00],[new Date(2025,9,17),5.00,6.00,7.00],[new Date(2025,9,20),4.80,4.90,5.00],[new Date(2025,9,22),4.80,4.90,5.00],[new Date(2025,9,24),8.00,9.00,10.00],[new Date(2025,9,29),4.80,4.90,5.00],[new Date(2025,10,12),6.00,6.50,7.00],[new Date(2025,10,14),6.00,6.50,7.00],[new Date(2025,10,17),6.00,6.50,7.00],[new Date(2025,10,19),5.00,5.50,6.00],[new Date(2025,10,26),11.00,11.50,12.00],[new Date(2025,11,19),10.00,10.00,10.00],[new Date(2025,11,22),15.00,15.00,15.00],[new Date(2026,1,02),20.00,20.00,20.00],[new Date(2026,1,04),8.00,8.00,8.00],[new Date(2026,1,06),8.00,8.00,8.00],[new Date(2026,1,09),8.00,8.00,8.00],[new Date(2026,1,11),10.00,10.00,10.00],[new Date(2026,1,13),4.50,4.75,5.00],[new Date(2026,1,27),8.00,9.00,10.00],[new Date(2026,2,06),8.00,9.00,10.00],[new Date(2026,2,09),9.00,9.50,10.00] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Chiova kg: Pre\u00e7os CEAGESP - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 0}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ &#8211;45.26%. Unidade: (kg). *Obs.: Varia\u00e7\u00e3o acentuada de pre\u00e7o pode representar inconsist\u00eancia de dados e deve ser conferido na fonte. Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h2>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h2>\n<table class=\"pClassNove\">\n<caption>\u00daltimos pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>27-02-2026<\/td>\n<td>8.00<\/td>\n<td>9.00<\/td>\n<td>10.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>06-03-2026<\/td>\n<td>8.00<\/td>\n<td>9.00<\/td>\n<td>10.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>09-03-2026<\/td>\n<td>9.00<\/td>\n<td>9.50<\/td>\n<td>10.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassOito\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h2>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>13 de agosto de 2025<\/td>\n<td>3.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>13 de agosto de 2025<\/td>\n<td><\/td>\n<td>4.00<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>27 de agosto de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>4.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de julho de 2025<\/td>\n<td>25.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de julho de 2025<\/td>\n<td><\/td>\n<td>28.00<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de julho de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>30.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Chiova kg'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. A CEAGESP \u2013 Companhia de Entrepostos e Armaz\u00e9ns Gerais de S\u00e3o Paulo, \u00e9 resultado da fus\u00e3o entre a CEASA, Centro Estadual de Abastecimento e a CAGESP, Companhia de Armaz\u00e9ns Gerais do estado de S\u00e3o Paulo. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceagesp.. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre\u00e7o Chiova kg, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 9.50 (kg) no dia 09\/03\/2026*, de acordo com o boletim Ceagesp, o que representa um aumento de 5.26% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 9.00. Veja mais detalhes&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[801,4,804],"tags":[],"class_list":["post-14533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceagesp","category-ceasa","category-pescados-sp"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/14533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=14533"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/14533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media\/6109"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=14533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=14533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=14533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}