{"id":21325,"date":"2020-11-17T16:23:49","date_gmt":"2020-11-17T16:23:49","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=21325"},"modified":"2026-03-15T12:29:07","modified_gmt":"2026-03-15T12:29:07","slug":"grafico-preco-tabela-uva-crimson-imp-chile-class-b-ceagesp-kg","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-uva-crimson-imp-chile-class-b-ceagesp-kg\/","title":{"rendered":"Pre\u00e7o Uva Crimson Imp. Chile Class. B kg cota\u00e7\u00e3o Ceagesp"},"content":{"rendered":"<p>Pre\u00e7o Uva Crimson Imp. Chile Classifica\u00e7\u00e3o B kg, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 15.63 (kg)<\/strong> no dia 11\/03\/2026*, de acordo com o boletim Ceagesp, o que representa um aumento de 2.24% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 15.28. O menor pre\u00e7o encontrado neste per\u00edodo foi de R$ 10.00 em 07 de julho de 2025 e o maior foi de R$ 19.00 em 09 de abril de 2025. Veja mais detalhes Ceagesp, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11 de mar\u00e7o de 2026<\/td>\n<td>15.00<\/td>\n<td>15.63<\/td>\n<td>16.25<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Gr\u00e1fico de pre\u00e7os recentes do produto Uva Crimson Imp. Chile Class. B kg<\/h2>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,2,28),12.00,13.00,14.00],[new Date(2025,2,31),13.00,14.00,15.00],[new Date(2025,3,02),13.00,14.00,15.00],[new Date(2025,3,09),18.00,18.50,19.00],[new Date(2025,3,11),17.68,18.19,18.68],[new Date(2025,3,14),12.50,13.00,13.50],[new Date(2025,3,16),14.77,15.28,15.77],[new Date(2025,3,23),13.00,13.50,14.00],[new Date(2025,3,25),12.08,12.81,13.54],[new Date(2025,3,28),10.61,11.35,12.10],[new Date(2025,3,30),12.50,13.00,13.50],[new Date(2025,4,05),14.00,14.50,15.00],[new Date(2025,4,07),14.00,14.50,15.00],[new Date(2025,4,09),14.00,14.50,15.00],[new Date(2025,4,12),14.00,14.50,15.00],[new Date(2025,4,19),12.00,13.00,14.00],[new Date(2025,4,21),13.50,14.00,14.50],[new Date(2025,4,23),13.50,14.00,14.50],[new Date(2025,4,26),11.00,12.00,13.00],[new Date(2025,5,02),12.00,13.00,14.00],[new Date(2025,6,07),10.00,10.30,10.50],[new Date(2025,6,25),10.00,10.30,10.50],[new Date(2026,1,13),17.13,17.50,17.88],[new Date(2026,1,20),17.13,17.50,17.88],[new Date(2026,2,02),15.63,16.25,16.88],[new Date(2026,2,04),15.63,16.25,16.88],[new Date(2026,2,06),15.00,15.63,16.25],[new Date(2026,2,09),14.30,15.28,16.25],[new Date(2026,2,11),15.00,15.63,16.25] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Uva Crimson Imp. Chile Class. B kg: Pre\u00e7os CEAGESP - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 5}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ &#8211;9.33%. Unidade: (kg). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h2>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h2>\n<table class=\"pClassNove\">\n<caption>\u00daltimos pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>20-02-2026<\/td>\n<td>17.13<\/td>\n<td>17.50<\/td>\n<td>17.88<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>02-03-2026<\/td>\n<td>15.63<\/td>\n<td>16.25<\/td>\n<td>16.88<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>04-03-2026<\/td>\n<td>15.63<\/td>\n<td>16.25<\/td>\n<td>16.88<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>06-03-2026<\/td>\n<td>15.00<\/td>\n<td>15.63<\/td>\n<td>16.25<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>09-03-2026<\/td>\n<td>14.30<\/td>\n<td>15.28<\/td>\n<td>16.25<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11-03-2026<\/td>\n<td>15.00<\/td>\n<td>15.63<\/td>\n<td>16.25<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassOito\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h2>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>07 de julho de 2025<\/td>\n<td>10.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>07 de julho de 2025<\/td>\n<td><\/td>\n<td>10.30<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>07 de julho de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>10.50<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>09 de abril de 2025<\/td>\n<td>18.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>09 de abril de 2025<\/td>\n<td><\/td>\n<td>18.50<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>09 de abril de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>19.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Uva Crimson Imp. Chile Class. B kg'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. A CEAGESP \u2013 Companhia de Entrepostos e Armaz\u00e9ns Gerais de S\u00e3o Paulo, \u00e9 resultado da fus\u00e3o entre a CEASA, Centro Estadual de Abastecimento e a CAGESP, Companhia de Armaz\u00e9ns Gerais do estado de S\u00e3o Paulo. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceagesp.. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre\u00e7o Uva Crimson Imp. Chile Classifica\u00e7\u00e3o B kg, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 15.63 (kg) no dia 11\/03\/2026*, de acordo com o boletim Ceagesp, o que representa um aumento de 2.24% em rela\u00e7\u00e3o ao valor anterior que foi de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[801,4,802,1340],"tags":[],"class_list":["post-21325","post","type-post","status-publish","format-standard","hentry","category-ceagesp","category-ceasa","category-frutas-sp","category-uva-sp"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=21325"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21325\/revisions"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=21325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=21325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=21325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}