{"id":21484,"date":"2020-11-17T17:12:31","date_gmt":"2020-11-17T17:12:31","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=21484"},"modified":"2025-08-02T19:23:10","modified_gmt":"2025-08-02T19:23:10","slug":"grafico-preco-tabela-file-de-dourado-ceasa-porto-alegre-kg","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-file-de-dourado-ceasa-porto-alegre-kg\/","title":{"rendered":"Pre\u00e7o Fil\u00e9 De Dourado kg Ceasa Porto Alegre"},"content":{"rendered":"<p>Pre\u00e7o Fil\u00e9 De Dourado kg, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Porto Alegre (RS). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 67.36 (kg)<\/strong>* no dia 31\/07\/2025*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o ao valor anterior que tamb\u00e9m foi de R$ 67.36. O menor pre\u00e7o encontrado neste per\u00edodo foi de R$ 67.36 em 16 de abril de 2025 e o maior foi de R$ 67.37 em 22 de abril de 2025. Veja mais detalhes, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceasa<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>31 de julho de 2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Gr\u00e1fico de pre\u00e7os recentes do produto Fil\u00e9 De Dourado kg<\/h3>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,3,15),67.36,67.36,67.36],[new Date(2025,3,16),67.36,67.36,67.36],[new Date(2025,3,17),67.36,67.36,67.36],[new Date(2025,3,21),67.36,67.36,67.36],[new Date(2025,3,22),67.37,67.37,67.37],[new Date(2025,3,23),67.37,67.37,67.37],[new Date(2025,3,24),74.90,67.37,67.37],[new Date(2025,3,29),74.90,67.37,67.37],[new Date(2025,4,02),74.90,67.37,67.37],[new Date(2025,4,05),74.90,67.37,67.37],[new Date(2025,4,06),74.90,53.89,53.89],[new Date(2025,4,07),74.90,53.89,53.89],[new Date(2025,4,09),74.90,67.36,67.36],[new Date(2025,4,12),74.90,67.36,67.36],[new Date(2025,4,13),74.90,67.36,67.36],[new Date(2025,4,14),74.90,67.36,67.36],[new Date(2025,4,15),74.90,67.36,67.36],[new Date(2025,4,16),74.90,67.36,67.36],[new Date(2025,4,19),74.90,67.36,67.36],[new Date(2025,4,20),74.90,67.36,67.36],[new Date(2025,4,21),74.90,67.36,67.36],[new Date(2025,4,22),74.90,67.36,67.36],[new Date(2025,4,23),74.90,67.36,67.36],[new Date(2025,4,26),74.90,67.36,67.36],[new Date(2025,4,27),74.90,67.36,67.36],[new Date(2025,4,28),74.90,67.36,67.36],[new Date(2025,4,29),74.90,74.90,53.89],[new Date(2025,4,30),74.90,74.90,53.89],[new Date(2025,5,02),74.90,74.90,53.89],[new Date(2025,5,03),74.90,74.90,53.89],[new Date(2025,5,04),74.90,74.90,53.89],[new Date(2025,5,05),74.90,67.36,67.36],[new Date(2025,5,06),74.90,67.36,67.36],[new Date(2025,5,09),74.90,67.36,67.36],[new Date(2025,5,10),74.90,67.36,67.36],[new Date(2025,5,11),74.90,67.36,67.36],[new Date(2025,5,12),74.90,53.89,53.89],[new Date(2025,5,13),74.90,53.89,53.89],[new Date(2025,5,16),74.90,53.89,53.89],[new Date(2025,5,17),74.90,53.89,53.89],[new Date(2025,5,19),74.90,53.89,53.89],[new Date(2025,5,20),74.90,53.89,53.89],[new Date(2025,5,23),74.90,53.89,53.89],[new Date(2025,5,24),74.90,53.89,53.89],[new Date(2025,5,25),74.90,53.89,53.89],[new Date(2025,5,27),74.90,67.36,67.36],[new Date(2025,5,30),74.90,67.36,67.36],[new Date(2025,6,01),74.90,67.36,67.36],[new Date(2025,6,02),74.90,67.36,67.36],[new Date(2025,6,03),74.90,67.36,67.36],[new Date(2025,6,04),74.90,67.36,67.36],[new Date(2025,6,07),74.90,67.36,67.36],[new Date(2025,6,08),74.90,67.36,67.36],[new Date(2025,6,09),74.90,67.36,67.36],[new Date(2025,6,10),74.90,67.36,67.36],[new Date(2025,6,11),74.90,67.36,67.36],[new Date(2025,6,14),74.90,67.36,67.36],[new Date(2025,6,15),74.90,67.36,67.36],[new Date(2025,6,16),74.90,67.36,67.36],[new Date(2025,6,17),74.90,67.36,67.36],[new Date(2025,6,18),74.90,67.36,67.36],[new Date(2025,6,21),74.90,67.36,67.36],[new Date(2025,6,22),74.90,67.36,67.36],[new Date(2025,6,23),74.90,67.36,67.36],[new Date(2025,6,24),74.90,67.36,67.36],[new Date(2025,6,25),74.90,67.36,67.36],[new Date(2025,6,26),74.90,67.36,67.36],[new Date(2025,6,28),74.90,67.36,67.36],[new Date(2025,6,29),74.90,67.36,67.36],[new Date(2025,6,30),74.90,67.36,67.36],[new Date(2025,6,31),74.90,67.36,67.36] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Fil\u00e9 De Dourado kg: Pre\u00e7os Ceasa Porto Alegre - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 38}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ -0.00%. Unidade: (kg). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h3>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h3>\n<table class=\"pClassNove\">\n<caption>\u00daltimos Pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>03-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>04-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>07-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>08-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>09-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>10-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>11-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>14-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>15-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>16-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>17-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>18-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>21-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>22-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>23-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>24-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>25-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>26-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>28-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>29-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>30-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>31-07-2025<\/td>\n<td>74.90<\/td>\n<td>67.36<\/td>\n<td>67.36<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassSeteCinco\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h3>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de abril de 2025<\/td>\n<td>67.36<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>06 de maio de 2025<\/td>\n<td><\/td>\n<td>53.89<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>06 de maio de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>53.89<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>31 de julho de 2025<\/td>\n<td>74.90<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>29 de maio de 2025<\/td>\n<td><\/td>\n<td>74.90<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>22 de abril de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>67.37<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Fil\u00e9 De Dourado kg'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceasa Porto Alegre &#8211; RS. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 02\/08\/2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre\u00e7o Fil\u00e9 De Dourado kg, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Porto Alegre (RS). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 67.36 (kg)* no dia 31\/07\/2025*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o ao valor anterior&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1464,3626],"tags":[],"class_list":["post-21484","post","type-post","status-publish","format-standard","hentry","category-ceasa","category-ceasa-rs","category-file-rs"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=21484"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21484\/revisions"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=21484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=21484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=21484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}