{"id":21582,"date":"2020-11-17T21:34:56","date_gmt":"2020-11-17T21:34:56","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=21582"},"modified":"2026-03-15T12:06:27","modified_gmt":"2026-03-15T12:06:27","slug":"grafico-preco-tabela-banana-ouro-clim-prim-ceasa-caratinga-kg","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-banana-ouro-clim-prim-ceasa-caratinga-kg\/","title":{"rendered":"Pre\u00e7o Banana Ouro Clim Prim kg Ceasa Caratinga"},"content":{"rendered":"<p>Banana Ouro Clim Prim (kg), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Caratinga (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 4.30 (kg)<\/strong> no dia 12\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o ao valor anterior que tamb\u00e9m foi de R$ 4.30. Veja mais detalhes, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceasa<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>12 de mar\u00e7o de 2026<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Gr\u00e1fico de pre\u00e7os recentes do produto Banana Ouro Clim Prim kg<\/h3>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,7,11),3.50,3.50,3.50],[new Date(2025,7,14),3.00,3.00,3.00],[new Date(2025,7,18),3.50,3.50,3.50],[new Date(2025,7,21),3.50,3.50,3.50],[new Date(2025,8,01),3.25,3.25,3.25],[new Date(2025,8,04),4.30,4.30,4.30],[new Date(2025,8,08),4.33,4.33,4.33],[new Date(2025,8,11),4.30,4.30,4.30],[new Date(2025,8,15),4.30,4.30,4.30],[new Date(2025,8,18),4.30,4.30,4.30],[new Date(2025,8,22),4.30,4.30,4.30],[new Date(2025,8,25),4.30,4.30,4.30],[new Date(2025,9,02),4.30,4.30,4.30],[new Date(2025,9,06),4.30,4.30,4.30],[new Date(2025,9,09),4.30,4.30,4.30],[new Date(2025,9,13),4.30,4.30,4.30],[new Date(2025,9,16),4.30,4.30,4.30],[new Date(2025,9,20),4.30,4.30,4.30],[new Date(2025,9,23),4.00,4.00,4.00],[new Date(2025,9,27),4.30,4.30,4.30],[new Date(2025,9,30),4.30,4.30,4.30],[new Date(2025,10,03),4.30,4.30,4.30],[new Date(2025,10,06),4.30,4.30,4.30],[new Date(2025,10,10),4.30,4.30,4.30],[new Date(2025,10,17),4.30,4.30,4.30],[new Date(2025,10,20),4.30,4.30,4.30],[new Date(2025,10,24),4.33,4.33,4.33],[new Date(2025,10,27),4.30,4.30,4.30],[new Date(2025,11,01),4.30,4.30,4.30],[new Date(2025,11,04),4.30,4.30,4.30],[new Date(2025,11,11),4.30,4.30,4.30],[new Date(2025,11,15),4.30,4.30,4.30],[new Date(2025,11,18),4.30,4.30,4.30],[new Date(2025,11,22),4.30,4.30,4.30],[new Date(2025,11,29),4.33,4.33,4.33],[new Date(2026,0,08),4.30,4.30,4.30],[new Date(2026,0,12),4.33,4.33,4.33],[new Date(2026,0,15),4.33,4.33,4.33],[new Date(2026,0,19),4.30,4.30,4.30],[new Date(2026,0,22),4.30,4.30,4.30],[new Date(2026,0,26),4.66,4.66,4.66],[new Date(2026,0,29),4.33,4.33,4.33],[new Date(2026,1,02),4.30,4.30,4.30],[new Date(2026,1,05),4.30,4.30,4.30],[new Date(2026,1,26),4.30,4.30,4.30],[new Date(2026,2,02),4.30,4.30,4.30],[new Date(2026,2,09),4.30,4.30,4.30],[new Date(2026,2,12),4.30,4.30,4.30] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Banana Ouro Clim Prim kg: Pre\u00e7os Ceasa Caratinga - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 1}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ +0.86%. Unidade: (kg). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h3>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h3>\n<table class=\"pClassNove\">\n<caption>\u00daltimos Pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>26-02-2026<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>02-03-2026<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>09-03-2026<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>12-03-2026<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>4.30<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassSeteCinco\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h3>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de agosto de 2025<\/td>\n<td>3.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de agosto de 2025<\/td>\n<td><\/td>\n<td>3.00<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>14 de agosto de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>3.00<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>26 de janeiro de 2026<\/td>\n<td>4.66<\/td>\n<td><\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>26 de janeiro de 2026<\/td>\n<td><\/td>\n<td>4.66<\/td>\n<td><\/td>\n<td>kg<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>26 de janeiro de 2026<\/td>\n<td><\/td>\n<td><\/td>\n<td>4.66<\/td>\n<td>kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Banana Ouro Clim Prim kg'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceasa Caratinga &#8211; MG. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banana Ouro Clim Prim (kg), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Caratinga (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 4.30 (kg) no dia 12\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o ao valor anterior&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2036,4,2020,2021],"tags":[],"class_list":["post-21582","post","type-post","status-publish","format-standard","hentry","category-banana-mg","category-ceasa","category-ceasa-mg","category-frutas-mg"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=21582"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21582\/revisions"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=21582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=21582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=21582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}