{"id":21770,"date":"2020-11-17T19:42:27","date_gmt":"2020-11-17T19:42:27","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=21770"},"modified":"2026-03-15T12:25:30","modified_gmt":"2026-03-15T12:25:30","slug":"grafico-preco-tabela-crista-de-galo-ceagesp-mc","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-crista-de-galo-ceagesp-mc\/","title":{"rendered":"Pre\u00e7os Ceagesp Crista-de-galo por mc"},"content":{"rendered":"<p>Pre\u00e7o Crista-de-galo mc, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 15.00 (mc)<\/strong> no dia 11\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceagesp, o que representa uma queda de -20.00% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 18.00. O menor pre\u00e7o encontrado neste per\u00edodo foi de R$ 10.00 em 27 de fevereiro de 2026 e o maior foi de R$ 20.00 em 25 de fevereiro de 2026. Veja mais detalhes Ceagesp, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11 de mar\u00e7o de 2026<\/td>\n<td>14.00<\/td>\n<td>15.00<\/td>\n<td>16.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Gr\u00e1fico de pre\u00e7os recentes do produto Crista-de-galo mc<\/h2>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,10,26),13.00,14.00,15.00],[new Date(2026,0,21),15.00,16.00,17.00],[new Date(2026,0,23),15.00,16.00,17.00],[new Date(2026,0,28),15.00,16.00,17.00],[new Date(2026,0,30),13.00,14.00,15.00],[new Date(2026,1,11),15.00,16.00,17.00],[new Date(2026,1,13),14.43,15.42,16.43],[new Date(2026,1,20),14.43,15.42,16.43],[new Date(2026,1,25),18.00,19.00,20.00],[new Date(2026,1,27),10.00,13.00,15.00],[new Date(2026,2,04),15.00,17.00,20.00],[new Date(2026,2,06),15.00,18.00,20.00],[new Date(2026,2,11),14.00,15.00,16.00] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Crista-de-galo mc: Pre\u00e7os CEAGESP - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 5}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ &#8211;1.16%. Unidade: (mc). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h2>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h2>\n<table class=\"pClassNove\">\n<caption>\u00daltimos pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>20-02-2026<\/td>\n<td>14.43<\/td>\n<td>15.42<\/td>\n<td>16.43<\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>25-02-2026<\/td>\n<td>18.00<\/td>\n<td>19.00<\/td>\n<td>20.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>27-02-2026<\/td>\n<td>10.00<\/td>\n<td>13.00<\/td>\n<td>15.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>04-03-2026<\/td>\n<td>15.00<\/td>\n<td>17.00<\/td>\n<td>20.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>06-03-2026<\/td>\n<td>15.00<\/td>\n<td>18.00<\/td>\n<td>20.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11-03-2026<\/td>\n<td>14.00<\/td>\n<td>15.00<\/td>\n<td>16.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassOito\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h2>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>27 de fevereiro de 2026<\/td>\n<td>10.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>27 de fevereiro de 2026<\/td>\n<td><\/td>\n<td>13.00<\/td>\n<td><\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>26 de novembro de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>15.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>25 de fevereiro de 2026<\/td>\n<td>18.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>25 de fevereiro de 2026<\/td>\n<td><\/td>\n<td>19.00<\/td>\n<td><\/td>\n<td>mc<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>25 de fevereiro de 2026<\/td>\n<td><\/td>\n<td><\/td>\n<td>20.00<\/td>\n<td>mc<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Crista-de-galo mc'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. A CEAGESP \u2013 Companhia de Entrepostos e Armaz\u00e9ns Gerais de S\u00e3o Paulo, \u00e9 resultado da fus\u00e3o entre a CEASA, Centro Estadual de Abastecimento e a CAGESP, Companhia de Armaz\u00e9ns Gerais do estado de S\u00e3o Paulo. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceagesp.. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre\u00e7o Crista-de-galo mc, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 15.00 (mc) no dia 11\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceagesp, o que representa uma queda de -20.00% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 18.00&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[801,4,3330],"tags":[],"class_list":["post-21770","post","type-post","status-publish","format-standard","hentry","category-ceagesp","category-ceasa","category-crista-sp"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=21770"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/21770\/revisions"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=21770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=21770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=21770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}