{"id":6477,"date":"2020-11-17T15:09:52","date_gmt":"2020-11-17T15:09:52","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=6477"},"modified":"2026-03-15T12:33:51","modified_gmt":"2026-03-15T12:33:51","slug":"grafico-preco-tabela-estrelicia-class-cabo-longo-ceagesp-dz","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-estrelicia-class-cabo-longo-ceagesp-dz\/","title":{"rendered":"Ceagesp pre\u00e7os Estrel\u00edcia Class. Cabo Longo dz"},"content":{"rendered":"<p>Pre\u00e7o Estrel\u00edcia Classifica\u00e7\u00e3o Cabo Longo dz, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 24.00 (dz)<\/strong> no dia 11\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceagesp, o que representa uma queda de -4.17% em rela\u00e7\u00e3o ao valor anterior que foi de R$ 25.00. O menor pre\u00e7o encontrado neste per\u00edodo foi de R$ 11.00 em 11 de abril de 2025 e o maior foi de R$ 30.00 em 09 de maio de 2025. Veja mais detalhes Ceagesp, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11 de mar\u00e7o de 2026<\/td>\n<td>23.00<\/td>\n<td>24.00<\/td>\n<td>25.00<\/td>\n<td>dz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Gr\u00e1fico de pre\u00e7os recentes do produto Estrel\u00edcia Class. Cabo Longo dz<\/h2>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,2,19),13.00,14.00,15.00],[new Date(2025,2,21),13.00,14.00,15.00],[new Date(2025,2,26),13.00,14.00,15.00],[new Date(2025,3,02),13.00,14.00,15.00],[new Date(2025,3,04),13.00,14.00,15.00],[new Date(2025,3,11),11.00,13.00,15.00],[new Date(2025,3,16),15.00,18.00,20.00],[new Date(2025,3,23),16.00,18.00,20.00],[new Date(2025,4,09),25.00,27.00,30.00],[new Date(2025,6,30),25.00,28.00,30.00],[new Date(2025,7,13),28.00,29.00,30.00],[new Date(2025,8,26),13.00,14.00,15.00],[new Date(2025,9,29),15.00,27.00,30.00],[new Date(2026,1,06),18.00,19.00,20.00],[new Date(2026,2,06),20.00,25.00,30.00],[new Date(2026,2,11),23.00,24.00,25.00] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Estrel\u00edcia Class. Cabo Longo dz: Pre\u00e7os CEAGESP - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 4}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ +11.63%. Unidade: (dz). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h2>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h2>\n<table class=\"pClassNove\">\n<caption>\u00daltimos pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleI\">\n<td>06-03-2026<\/td>\n<td>20.00<\/td>\n<td>25.00<\/td>\n<td>30.00<\/td>\n<td>dz<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>11-03-2026<\/td>\n<td>23.00<\/td>\n<td>24.00<\/td>\n<td>25.00<\/td>\n<td>dz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassOito\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h2>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>11 de abril de 2025<\/td>\n<td>11.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>dz<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>11 de abril de 2025<\/td>\n<td><\/td>\n<td>13.00<\/td>\n<td><\/td>\n<td>dz<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>21 de mar\u00e7o de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>15.00<\/td>\n<td>dz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceagesp<\/h2>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>13 de agosto de 2025<\/td>\n<td>28.00<\/td>\n<td><\/td>\n<td><\/td>\n<td>dz<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>13 de agosto de 2025<\/td>\n<td><\/td>\n<td>29.00<\/td>\n<td><\/td>\n<td>dz<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>09 de maio de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>30.00<\/td>\n<td>dz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Estrel\u00edcia Class. Cabo Longo dz'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. A CEAGESP \u2013 Companhia de Entrepostos e Armaz\u00e9ns Gerais de S\u00e3o Paulo, \u00e9 resultado da fus\u00e3o entre a CEASA, Centro Estadual de Abastecimento e a CAGESP, Companhia de Armaz\u00e9ns Gerais do estado de S\u00e3o Paulo. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceagesp.. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre\u00e7o Estrel\u00edcia Classifica\u00e7\u00e3o Cabo Longo dz, gr\u00e1fico e tabela de cota\u00e7\u00e3o di\u00e1ria, conforme dados da Ceagesp (SP). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 24.00 (dz) no dia 11\/03\/2026*, de acordo com a \u00faltima consulta no boletim Ceagesp, o que representa uma queda de -4.17% em rela\u00e7\u00e3o ao valor anterior que foi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[801,4,1378],"tags":[],"class_list":["post-6477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceagesp","category-ceasa","category-estrelicia-sp"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/6477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=6477"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/6477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media\/6109"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=6477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=6477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=6477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}