{"id":6962,"date":"2020-11-17T12:46:34","date_gmt":"2020-11-17T12:46:34","guid":{"rendered":"http:\/\/precota.com.br\/agro\/?p=6962"},"modified":"2026-03-15T12:14:10","modified_gmt":"2026-03-15T12:14:10","slug":"grafico-preco-tabela-agua-sanitaria-ceasa-belo-horizonte-cx-8x2000-ml","status":"publish","type":"post","link":"https:\/\/precota.com.br\/agro\/grafico-preco-tabela-agua-sanitaria-ceasa-belo-horizonte-cx-8x2000-ml\/","title":{"rendered":"Pre\u00e7o Agua Sanitaria cx 8&#215;2000 ml Ceasa Belo Horizonte"},"content":{"rendered":"<p>Agua Sanitaria (cx 8&#215;2000 ml), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Belo Horizonte (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de <strong>R$ 35.84 (cx 8&#215;2000 ml)<\/strong> no dia 18\/02\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o ao valor anterior que tamb\u00e9m foi de R$ 35.84. Veja mais detalhes, abaixo. <\/p>\n<h2>Pre\u00e7os recentes &#8211; Ceasa<\/h2>\n<table class=\"pClassNove\">\n<caption>Cota\u00e7\u00e3o mais recente<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>18 de fevereiro de 2026<\/td>\n<td>35.84<\/td>\n<td>35.84<\/td>\n<td>39.84<\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Gr\u00e1fico de pre\u00e7os recentes do produto Agua Sanitaria cx 8&#215;2000 ml<\/h3>\n<p> <script type=\"text\/javascript\" src=\"https:\/\/www.gstatic.com\/charts\/loader.js\"><\/script> <script type=\"text\/javascript\"> var largura = document.body.clientWidth - 20; if (largura > 615){ var largura = 620; } google.charts.load(\"current\", {\"packages\":[\"corechart\"],\"language\": \"pt\"}); google.charts.setOnLoadCallback(drawChart); function drawChart() { var data = google.visualization.arrayToDataTable([ [\"Year\", {label: \"Minimo\", type: \"number\"},{label: \"Comum\", type: \"number\"},{label: \"M\u00e1ximo\", type: \"number\"}] ,[new Date(2025,5,16),34.38,34.38,38.32],[new Date(2025,6,16),34.38,34.38,36.72],[new Date(2025,10,12),31.84,35.84,39.84],[new Date(2025,11,17),35.84,35.84,39.84],[new Date(2026,0,14),35.84,35.84,39.84],[new Date(2026,1,18),35.84,35.84,39.84] ]); var options = { legend: { position: \"bottom\", maxLines: 1}, chartArea: {width: \"100%\", height: \"100%\", left: 5, top: 20, right:5, bottom:25}, series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 3: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"} }, colors: [\"#ff7f2a\",\"#1851a7\",\"#ffcc00\"], explorer: { actions: [\"dragToZoom\", \"rightClickToReset\"], maxZoomIn: .02 }, title: \"Agua Sanitaria cx 8x2000 ml: Pre\u00e7os Ceasa Belo Horizonte - precota.com.br\/agro\", titlePosition: \"top\", titleTextStyle: { }, crosshair: { trigger: \"none\", orientation: \"horizontal\", opacity: 0.8, }, trendlines: { 1: { type: \"linear\", degree: 3, visibleInLegend: false, pointSize: 1, opacity: 0.2, tooltip: false } }, hAxis: {textPosition: \"in\", title: \"\", viewWindowMode: \"explicit\", viewWindow: {}, format: \"dd-MM-YY\", gridlines: {color: \"#ebebf5\"}}, vAxis: {textPosition: \"in\", title: \"\", format: \"currency\", viewWindowMode: \"explicit\", viewWindow: {min: 27}, gridlines: {color: \"#ebebf5\"}}, curveType: \"\", width: largura, height: 300, backgroundColor: {stroke: \"blue\", fill:\"#f6f6fd\", strokeWidth: 1} }; var chart = new google.visualization.LineChart(document.getElementById(\"chart_div\")); chart.draw(data, options); } <\/script> <\/p>\n<div id=\"chart_div\" class=\"graficoArea\"><\/div>\n<p> <span class=\"pClassOito\">Tend\u00eancia do \u00faltimo trimestre: ~ -0.00%. Unidade: (cx 8&#215;2000 ml). Clique e arraste para zoom; bot\u00e3o direito reseta.<br \/> Legendas:<br \/> <span class=\"colorABR\">M\u00ednimo<\/span>: Pre\u00e7o m\u00ednimo.<br \/> <span class=\"colorCM\">Comum<\/span>: Pre\u00e7o mais comum ao consumidor.<br \/> <span class=\"colorMax\">M\u00e1ximo<\/span>: Pre\u00e7o m\u00e1ximo.<\/span><\/p>\n<h3>Tabela da cota\u00e7\u00e3o de pre\u00e7os dos \u00faltimos 30 dias<\/h3>\n<table class=\"pClassNove\">\n<caption>\u00daltimos Pre\u00e7os<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleG\">\n<td>18-02-2026<\/td>\n<td>35.84<\/td>\n<td>35.84<\/td>\n<td>39.84<\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span class=\"pClassSeteCinco\">Pre\u00e7os em real (R$).<\/span> <\/p>\n<h3>Menores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais baixos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>12 de novembro de 2025<\/td>\n<td>31.84<\/td>\n<td><\/td>\n<td><\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de julho de 2025<\/td>\n<td><\/td>\n<td>34.38<\/td>\n<td><\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>16 de julho de 2025<\/td>\n<td><\/td>\n<td><\/td>\n<td>36.72<\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Maiores pre\u00e7os encontrados nos \u00faltimos meses &#8211; Ceasa<\/h3>\n<table class=\"pClassNove\">\n<caption>Pre\u00e7os mais altos<\/caption>\n<tbody>\n<tr class=\"trStyleA\">\n<td>Data<\/td>\n<td>M\u00ednimo<\/td>\n<td>Comum<\/td>\n<td>M\u00e1ximo<\/td>\n<td>Embalagem<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>17 de dezembro de 2025<\/td>\n<td>35.84<\/td>\n<td><\/td>\n<td><\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>12 de novembro de 2025<\/td>\n<td><\/td>\n<td>35.84<\/td>\n<td><\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<tr class=\"trStyleH\">\n<td>18 de fevereiro de 2026<\/td>\n<td><\/td>\n<td><\/td>\n<td>39.84<\/td>\n<td>cx 8&#215;2000 ml<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p class='pClassOito'>Verifique <a href='https:\/\/precota.com.br\/agro\/?s=Agua Sanitaria cx 8x2000 ml'>pre\u00e7os em outras regi\u00f5es<\/a>. Veja tamb\u00e9m pre\u00e7os de outros produtos no <a href='https:\/\/precota.com.br\/agro\/'>\u00edndice<\/a>.<\/p>\n<p class='pClassOito'>As Ceasas, Centrais de Abastecimento, s\u00e3o empresas estatais ou de capital misto destinadas a promover, desenvolver, regular, dinamizar e organizar a comercializa\u00e7\u00e3o de produtos da hortifruticultura (perec\u00edveis) a n\u00edvel de atacado em uma regi\u00e3o de a\u00e7\u00e3o. Este site n\u00e3o possui rela\u00e7\u00e3o com a Ceasa Belo Horizonte &#8211; MG. *Recomendamos que verifique a precis\u00e3o desses dados antes de aplic\u00e1-los em contextos cr\u00edticos ou de import\u00e2ncia significativa, uma vez que n\u00e3o s\u00e3o auditados. Assim, cabe exclusivamente ao usu\u00e1rio decidir e assumir a responsabilidade de como pretender utilizar essas informa\u00e7\u00f5es. A \u00faltima atualiza\u00e7\u00e3o desta p\u00e1gina ocorreu em 15\/03\/2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agua Sanitaria (cx 8&#215;2000 ml), pre\u00e7o, gr\u00e1fico e tabela de pre\u00e7os de cota\u00e7\u00e3o, conforme dados da Ceasa Belo Horizonte (MG). O \u00faltimo pre\u00e7o comum encontrado deste produto foi de R$ 35.84 (cx 8&#215;2000 ml) no dia 18\/02\/2026*, de acordo com a \u00faltima consulta no boletim Ceasa, o que representa uma varia\u00e7\u00e3o de 0.00% em rela\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2082,4,2020],"tags":[],"class_list":["post-6962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua-mg","category-ceasa","category-ceasa-mg"],"_links":{"self":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/6962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/comments?post=6962"}],"version-history":[{"count":0,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/posts\/6962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media\/6109"}],"wp:attachment":[{"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/media?parent=6962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/categories?post=6962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/precota.com.br\/agro\/wp-json\/wp\/v2\/tags?post=6962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}